{"id":9915,"date":"2025-11-21T08:54:33","date_gmt":"2025-11-21T08:54:33","guid":{"rendered":"https:\/\/lirolight.com\/?post_type=product&#038;p=9915"},"modified":"2026-08-27T08:41:59","modified_gmt":"2026-08-27T08:41:59","slug":"liro-lite-ip65-new-waterproof-laser-beam-300w-moving-head-lights","status":"publish","type":"product","link":"https:\/\/lirolight.com\/de\/produkt\/liro-lite-ip65-new-waterproof-laser-beam-300w-moving-head-lights\/","title":{"rendered":"LIRO-LITE IP65 New Waterproof Laser Beam 300w Moving Head Lights"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:#000000\" class=\"has-inline-color has-white-color\">LR-IP BEAM300<\/mark> <\/strong>                  <\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Bilder:<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/1-1024x1024.jpg\" alt=\"\" class=\"wp-image-11261\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/1-1024x1024.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/1-300x300.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/1-150x150.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/1-768x768.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/1-1536x1536.jpg 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/1-2048x2048.jpg 2048w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/1-12x12.jpg 12w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/1-990x990.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/1-441x441.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/1-100x100.jpg 100w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/1-800x800.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/1-40x40.jpg 40w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-1024x1024.jpg\" alt=\"\" class=\"wp-image-11263 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-1024x1024.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-300x300.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-150x150.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-768x768.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-1536x1536.jpg 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-2048x2048.jpg 2048w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-12x12.jpg 12w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-990x990.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-441x441.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-100x100.jpg 100w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-800x800.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-40x40.jpg 40w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/1024;\" \/><noscript><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-1024x1024.jpg\" alt=\"\" class=\"wp-image-11263\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-1024x1024.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-300x300.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-150x150.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-768x768.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-1536x1536.jpg 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-2048x2048.jpg 2048w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-12x12.jpg 12w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-990x990.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-441x441.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-100x100.jpg 100w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-800x800.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/4-40x40.jpg 40w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-1024x1024.jpg\" alt=\"\" class=\"wp-image-11262 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-1024x1024.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-300x300.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-150x150.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-768x768.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-1536x1536.jpg 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-2048x2048.jpg 2048w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-12x12.jpg 12w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-990x990.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-441x441.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-100x100.jpg 100w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-800x800.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-40x40.jpg 40w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/1024;\" \/><noscript><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-1024x1024.jpg\" alt=\"\" class=\"wp-image-11262\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-1024x1024.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-300x300.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-150x150.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-768x768.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-1536x1536.jpg 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-2048x2048.jpg 2048w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-12x12.jpg 12w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-990x990.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-441x441.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-100x100.jpg 100w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-800x800.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/2-1-40x40.jpg 40w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-1024x1024.jpg\" alt=\"\" class=\"wp-image-11266 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-1024x1024.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-300x300.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-150x150.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-768x768.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-1536x1536.jpg 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-2048x2048.jpg 2048w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-12x12.jpg 12w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-990x990.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-441x441.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-100x100.jpg 100w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-800x800.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-40x40.jpg 40w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/1024;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-1024x1024.jpg\" alt=\"\" class=\"wp-image-11266\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-1024x1024.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-300x300.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-150x150.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-768x768.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-1536x1536.jpg 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-2048x2048.jpg 2048w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-12x12.jpg 12w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-990x990.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-441x441.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-100x100.jpg 100w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-800x800.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/11-40x40.jpg 40w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Spezifikation:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Wide Voltage: AC90V-235V 50-60Hz<\/li>\n\n\n\n<li>Power Supply: 500W<\/li>\n\n\n\n<li>Light Source System: 260W Laser Light Source<\/li>\n\n\n\n<li>Color Temperature: 7900\u00b1500K<\/li>\n\n\n\n<li>Color :14 colors + Rainbow Effect + Atomization Function<\/li>\n\n\n\n<li>Static gobo: 16 Static gobos+ White Light<\/li>\n\n\n\n<li>Focusing System: Electronic Focusing<\/li>\n\n\n\n<li>Atomization: Features atomization function, enabling a soft light effect<\/li>\n\n\n\n<li>Prisms: 8+16 prisms, dual-prism rotation, adjustable speed.<\/li>\n\n\n\n<li>Motor: Three-phase motor used on the PAN and TILT, ensuring high stability of the lamp&#8217;s speed and accurate positioning angle!<\/li>\n\n\n\n<li>Dimming Curve: 0%-100% linear dimming, smooth and flicker-free<\/li>\n\n\n\n<li>Beam Angle: 0-2\u00b0<\/li>\n\n\n\n<li>Channels: 16 channels<\/li>\n\n\n\n<li>Lens Diameter: 180mm<\/li>\n\n\n\n<li>Waterproof Rating: IP66<\/li>\n\n\n\n<li>Control Method 1: DMX 512<\/li>\n\n\n\n<li>Display: LCD display, adaptable to different installation positions, 180\u00b0 rotatable<\/li>\n\n\n\n<li>Horizontal and Vertical: High-precision three-phase motor, accurate positioning, smooth operation, automatic positioning correction<\/li>\n\n\n\n<li>Horizontal: 540\u00b0 rotation, 8\/16-bit resolution, with fine-tuning<\/li>\n\n\n\n<li>Vertical: 270\u00b0 rotation, 8\/16-bit resolution, with fine-tuning<\/li>\n\n\n\n<li>Housing: All die-cast aluminum<\/li>\n\n\n\n<li>Light Body Dimensions: 705*375*300cm<\/li>\n\n\n\n<li>Net Weight: 27KG<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Parameter:<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Breite Spannung<\/td><td>AC100-240V,50\/60Hz<\/td><\/tr><tr><td>Lebenserwartung<\/td><td>50.000 Stunden<\/td><\/tr><tr><td>Strom<\/td><td>500W<\/td><\/tr><tr><td>LED-Quelle<\/td><td>260W Laser Light Source<\/td><\/tr><tr><td>Optische Linse<\/td><td>180mm<\/td><\/tr><tr><td>Strahlwinkel<\/td><td>0-2\u00b0<\/td><\/tr><tr><td>Farben<\/td><td>14 colors + Rainbow Effect + Atomization Function<\/td><\/tr><tr><td>Muster<\/td><td>16 Static gobos+ White Light<\/td><\/tr><tr><td>Prismen<\/td><td> 8+16 prisms, dual-prism rotation, adjustable speed.<\/td><\/tr><tr><td>Steuerkan\u00e4le:<\/td><td>16CH<\/td><\/tr><tr><td>Anzeige<\/td><td>LCD-Anzeige<\/td><\/tr><tr><td>Verbindungsmodus<\/td><td>DMX\/RDM\/Master-Slave\/Auto\/Artnet<\/td><\/tr><tr><td>PowerCon Eingang\/Ausgang<\/td><td>True1-Stecker<\/td><\/tr><tr><td>IP-Einstufung<\/td><td>IP66<\/td><\/tr><tr><td>Nettogewicht<\/td><td>27KG<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Zeit der Vorstellung:<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"1024\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-602x1024.jpg\" alt=\"\" class=\"wp-image-9923 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-602x1024.jpg 602w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-176x300.jpg 176w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-768x1307.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-903x1536.jpg 903w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-7x12.jpg 7w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-990x1685.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-441x750.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-300x511.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-800x1361.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-150x255.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-294x500.jpg 294w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-24x40.jpg 24w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1.jpg 1170w\" data-sizes=\"(max-width: 602px) 100vw, 602px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 602px; --smush-placeholder-aspect-ratio: 602\/1024;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"1024\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-602x1024.jpg\" alt=\"\" class=\"wp-image-9923\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-602x1024.jpg 602w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-176x300.jpg 176w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-768x1307.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-903x1536.jpg 903w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-7x12.jpg 7w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-990x1685.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-441x750.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-300x511.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-800x1361.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-150x255.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-294x500.jpg 294w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1-24x40.jpg 24w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c1.jpg 1170w\" sizes=\"(max-width: 602px) 100vw, 602px\" \/><\/noscript><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"594\" height=\"1024\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-594x1024.jpg\" alt=\"\" class=\"wp-image-9924 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-594x1024.jpg 594w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-174x300.jpg 174w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-768x1324.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-891x1536.jpg 891w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-7x12.jpg 7w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-990x1707.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-441x760.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-300x517.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-800x1379.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-150x259.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-23x40.jpg 23w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2.jpg 1170w\" data-sizes=\"(max-width: 594px) 100vw, 594px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 594px; --smush-placeholder-aspect-ratio: 594\/1024;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"594\" height=\"1024\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-594x1024.jpg\" alt=\"\" class=\"wp-image-9924\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-594x1024.jpg 594w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-174x300.jpg 174w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-768x1324.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-891x1536.jpg 891w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-7x12.jpg 7w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-990x1707.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-441x760.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-300x517.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-800x1379.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-150x259.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2-23x40.jpg 23w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/11\/\u6548\u679c2.jpg 1170w\" sizes=\"(max-width: 594px) 100vw, 594px\" \/><\/noscript><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Video-Link:<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.instagram.com\/p\/DRJv4r7EikG\" target=\"_blank\" rel=\"noopener\">https:\/\/www.instagram.com\/p\/DRJv4r7EikG<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>LR-IP BEAM300 Pictures: Specification: Parameters: Wide Voltage AC100-240V,50\/60Hz Lifespan 50,000 Hours Power 500W LED Source 260W Laser Light Source Optical Lens 180mm Beam Angle 0-2\u00b0 Colors 14 colors + Rainbow Effect + Atomization Function Patterns 16 Static gobos+ White Light Prisms 8+16 prisms, dual-prism rotation, adjustable speed. Control Channels: 16CH Display LCD display Connection mode [&hellip;]<\/p>","protected":false},"featured_media":11769,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[64,51],"product_tag":[494,497,496,194,107,115,160,495],"class_list":{"0":"post-9915","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ip-beam-bsw","7":"product_cat-waterproof-series","8":"product_tag-beam-lights","9":"product_tag-beam-moving-head-light","10":"product_tag-laser-light","11":"product_tag-led-bar-light","12":"product_tag-movinghead","13":"product_tag-movingheadlights","14":"product_tag-stagelights","15":"product_tag-waterproof-laser-beam","17":"first","18":"instock","19":"shipping-taxable","20":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/lirolight.com\/de\/wp-json\/wp\/v2\/product\/9915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lirolight.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lirolight.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lirolight.com\/de\/wp-json\/wp\/v2\/comments?post=9915"}],"version-history":[{"count":6,"href":"https:\/\/lirolight.com\/de\/wp-json\/wp\/v2\/product\/9915\/revisions"}],"predecessor-version":[{"id":11908,"href":"https:\/\/lirolight.com\/de\/wp-json\/wp\/v2\/product\/9915\/revisions\/11908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lirolight.com\/de\/wp-json\/wp\/v2\/media\/11769"}],"wp:attachment":[{"href":"https:\/\/lirolight.com\/de\/wp-json\/wp\/v2\/media?parent=9915"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lirolight.com\/de\/wp-json\/wp\/v2\/product_brand?post=9915"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lirolight.com\/de\/wp-json\/wp\/v2\/product_cat?post=9915"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lirolight.com\/de\/wp-json\/wp\/v2\/product_tag?post=9915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}