{"id":11835,"date":"2026-08-10T06:53:58","date_gmt":"2026-08-10T06:53:58","guid":{"rendered":"https:\/\/lirolight.com\/?post_type=product&#038;p=11835"},"modified":"2026-08-27T08:38:23","modified_gmt":"2026-08-27T08:38:23","slug":"liro-lite-24x40w-rgbw-4in1-led-flood-light-ip66-strike-v-moving-wash-strobe-light","status":"publish","type":"product","link":"https:\/\/lirolight.com\/es\/producto\/liro-lite-24x40w-rgbw-4in1-led-flood-light-ip66-strike-v-moving-wash-strobe-light\/","title":{"rendered":"LIRO-LITE 24x40W RGBW 4IN1 LED Flood Light IP66 Strike V Moving Wash Strobe Light"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:#000000\" class=\"has-inline-color has-white-color\">LR-<strong><strong>IP <\/strong><\/strong>Strike V<\/mark><\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Fotos:<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/3.png\" alt=\"\" class=\"wp-image-11838 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 4000px; --smush-placeholder-aspect-ratio: 4000\/4000;\" \/><noscript><img decoding=\"async\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/3.png\" alt=\"\" class=\"wp-image-11838\"\/><\/noscript><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/5-1024x1024.png\" alt=\"\" class=\"wp-image-11840\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/5-1024x1024.png 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/5-300x300.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/5-150x150.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/5-768x768.png 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/5-1536x1536.png 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/5-2048x2048.png 2048w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/5-12x12.png 12w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/5-990x990.png 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/5-441x441.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/5-100x100.png 100w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/5-800x800.png 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/5-40x40.png 40w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/9.png\" alt=\"\" class=\"wp-image-11843 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 4000px; --smush-placeholder-aspect-ratio: 4000\/4000;\" \/><noscript><img decoding=\"async\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/9.png\" alt=\"\" class=\"wp-image-11843\"\/><\/noscript><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-1024x1024.jpg\" alt=\"\" class=\"wp-image-11196 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-1024x1024.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-300x300.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-150x150.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-768x768.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-1536x1536.jpg 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-2048x2048.jpg 2048w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-12x12.jpg 12w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-990x990.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-441x441.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-100x100.jpg 100w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-800x800.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-40x40.jpg 40w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/1024;\" \/><noscript><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-1024x1024.jpg\" alt=\"\" class=\"wp-image-11196\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-1024x1024.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-300x300.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-150x150.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-768x768.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-1536x1536.jpg 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-2048x2048.jpg 2048w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-12x12.jpg 12w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-990x990.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-441x441.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-100x100.jpg 100w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-800x800.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/04\/3-3-40x40.jpg 40w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-1024x1024.png\" alt=\"\" class=\"wp-image-11842 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-1024x1024.png 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-300x300.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-150x150.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-768x768.png 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-1536x1536.png 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-2048x2048.png 2048w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-12x12.png 12w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-990x990.png 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-441x441.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-100x100.png 100w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-800x800.png 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-500x500.png 500w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-40x40.png 40w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/1024;\" \/><noscript><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-1024x1024.png\" alt=\"\" class=\"wp-image-11842\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-1024x1024.png 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-300x300.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-150x150.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-768x768.png 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-1536x1536.png 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-2048x2048.png 2048w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-12x12.png 12w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-990x990.png 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-441x441.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-100x100.png 100w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-800x800.png 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-500x500.png 500w, https:\/\/lirolight.com\/wp-content\/uploads\/2026\/08\/6-40x40.png 40w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Especificaci\u00f3n\uff1a<\/font><\/font><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Input voltage: AC100-240V,50\/60Hz<\/li>\n\n\n\n<li>Total power: 700W;<\/li>\n\n\n\n<li>Main light source: 24\u00d740W RGBW LEDs;<\/li>\n\n\n\n<li>Fill light\uff1a24\u00d73W RGBW LEDs;<\/li>\n\n\n\n<li>Mean lifetime:&gt;20,000 hours;<\/li>\n\n\n\n<li>Connection method: DMX512 input\/output \/ power input\/output\/Network cable input\/output<\/li>\n\n\n\n<li><strong>Frost: Linear electronic frost<\/strong><\/li>\n\n\n\n<li>Dimmer and strobe: Linear electronic dimmer from 0% to 100%; Fast electronic strobe;<\/li>\n\n\n\n<li>Display and Main Control: LCD display with Chinese-English language switching capability;supports light information queries.<\/li>\n\n\n\n<li><strong>Channel options<\/strong><\/li>\n\n\n\n<li>Single-control\uff1a29CH\/222CH\/314CH\uff1b<\/li>\n\n\n\n<li>Dual-layer\uff1a30+144CH(174CH)\/30+192CH(222CH)\/30+240CH(270CH)\/30+288CH(318)<\/li>\n\n\n\n<li>Multi-layer Channel\uff1a30+72+72CH\/30+72+96CH\/30+96+72CH\/30+96+96CH\/30+120+120CH\/30+120+144CH\/30+144+120CH\/30+144+144CH<\/li>\n\n\n\n<li>Control mode: DMX512 control, Artnet protocol control, sACN protocol control, and support for<\/li>\n\n\n\n<li>RDM function; Upgrade the lights through DMX signal lines;<\/li>\n\n\n\n<li>Intelligent thermal management: Temperature sensing detection with adaptive fan speed<\/li>\n\n\n\n<li>regulation;<\/li>\n\n\n\n<li>Vertical scanning: 270\u00b0 (16-bit resolution)<\/li>\n\n\n\n<li>Features automatic error correction with reset functionality;<\/li>\n\n\n\n<li>Aspecto: Metal, negro<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Par\u00e1metro: <\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Tensi\u00f3n de entrada<\/td><td>AC 100V-240V 50\/60HZ<\/td><\/tr><tr><td>Lamp beads<\/td><td>24\u00d740W RGBW LEDs+24\u00d73W RGBW LEDs<\/td><\/tr><tr><td>Potencia<\/td><td>700W<\/td><\/tr><tr><td>Canal<\/td><td>Single-control\uff1a29CH\/222CH\/314CH\uff1b<br>Dual-layer\uff1a30+144CH(174CH)\/30+192CH(222CH)\/30+240CH(270CH)\/30+288CH(318)<br>Multi-layer Channel\uff1a30+72+72CH\/30+72+96CH\/30+96+72CH\/30+96+96CH\/30+120+120CH\/30+120+144CH\/30+144+120CH\/30+144+144CH<\/td><\/tr><tr><td>Frost<\/td><td><strong>Linear electronic frost<\/strong><\/td><\/tr><tr><td>Protection level<\/td><td>IP66<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Tama\u00f1o:<\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Hora del espect\u00e1culo:<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Enlace de v\u00eddeo:<\/h2>\n\n\n\n<p><a href=\"https:\/\/www.instagram.com\/reel\/DbvIiRUhX5x\" target=\"_blank\" rel=\"noopener\">https:\/\/www.instagram.com\/reel\/DbvIiRUhX5x<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>LR-IP Strike V Pictures: Specification\uff1a Parameter: Input voltage AC 100V-240V 50\/60HZ Lamp beads 24\u00d740W RGBW LEDs+24\u00d73W RGBW LEDs Power 700W Channel Single-control\uff1a29CH\/222CH\/314CH\uff1bDual-layer\uff1a30+144CH(174CH)\/30+192CH(222CH)\/30+240CH(270CH)\/30+288CH(318)Multi-layer Channel\uff1a30+72+72CH\/30+72+96CH\/30+96+72CH\/30+96+96CH\/30+120+120CH\/30+120+144CH\/30+144+120CH\/30+144+144CH Frost Linear electronic frost Protection level IP66 Size: Show time: Video Link: https:\/\/www.instagram.com\/reel\/DbvIiRUhX5x<\/p>","protected":false},"featured_media":11766,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[51,66],"product_tag":[728,725,420,421,723,419,422,78,645,423],"class_list":{"0":"post-11835","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-waterproof-series","7":"product_cat-ip-strobe-bar","8":"product_tag-color-strike-v","9":"product_tag-led-flood-light","10":"product_tag-led-static-strobe-wash","11":"product_tag-led-strobe-lights","12":"product_tag-moving-wash-strobe-light","13":"product_tag-rgbw-strobe-wash-light","14":"product_tag-stage-light","15":"product_tag-strobe","16":"product_tag-strobe-moving-head-stage-light","17":"product_tag-waterprooof-strobe-light","19":"first","20":"instock","21":"shipping-taxable","22":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/product\/11835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/comments?post=11835"}],"version-history":[{"count":5,"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/product\/11835\/revisions"}],"predecessor-version":[{"id":11884,"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/product\/11835\/revisions\/11884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/media\/11766"}],"wp:attachment":[{"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/media?parent=11835"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/product_brand?post=11835"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/product_cat?post=11835"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/product_tag?post=11835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}