{"id":8985,"date":"2025-07-30T03:26:41","date_gmt":"2025-07-30T03:26:41","guid":{"rendered":"https:\/\/lirolight.com\/?post_type=product&#038;p=8985"},"modified":"2026-08-28T00:29:13","modified_gmt":"2026-08-28T00:29:13","slug":"liro-lite-ip65-9x18w-led-rgbwa-uv-6in1-waterproof-dmx-wall-washer-bar-lights-led-battery-powered-wedding-uplight","status":"publish","type":"product","link":"https:\/\/lirolight.com\/es\/producto\/liro-lite-ip65-9x18w-led-rgbwa-uv-6in1-waterproof-dmx-wall-washer-bar-lights-led-battery-powered-wedding-uplight\/","title":{"rendered":"LIRO-LITE IP65 9x18W LED RGBWA UV 6IN1 Waterproof Dmx Wall Washer Bar Lights Led Battery Powered Wedding Uplight"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><mark style=\"background-color:#000000\" class=\"has-inline-color has-white-color\"><strong>Bater\u00eda LR-IP B918<\/strong><\/mark><\/h2>\n\n\n\n<p>Este ba\u00f1ador de pared impermeable IP65 9x18W RGBWA UV es la soluci\u00f3n perfecta alimentada por pilas para bodas y eventos. Con nueve LED 6 en 1 de alta potencia, ofrece una impresionante mezcla de colores y vibrantes efectos UV. Su dise\u00f1o robusto y resistente a la intemperie garantiza un rendimiento fiable tanto en interiores como en exteriores. Alimentado por una bater\u00eda de 13200 mAh, ofrece hasta 20 horas de luz monocolor o 7 horas en modo autom\u00e1tico. Con un tiempo de carga de 5 horas, proporciona una iluminaci\u00f3n brillante e inal\u00e1mbrica para cualquier ocasi\u00f3n, creando fondos atmosf\u00e9ricos inolvidables.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Fotos:<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2000\" height=\"1257\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-1-e1768270626348.png\" alt=\"\" class=\"wp-image-8986\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-1-e1768270626348.png 2000w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-1-e1768270626348-300x189.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-1-e1768270626348-1024x644.png 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-1-e1768270626348-768x483.png 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-1-e1768270626348-1536x965.png 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-1-e1768270626348-18x12.png 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-1-e1768270626348-990x622.png 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-1-e1768270626348-441x277.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-1-e1768270626348-800x503.png 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-1-e1768270626348-150x94.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-1-e1768270626348-60x38.png 60w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"2000\" height=\"2000\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2.png\" alt=\"\" class=\"wp-image-8987 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2.png 2000w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-300x300.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-1024x1024.png 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-150x150.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-768x768.png 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-1536x1536.png 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-12x12.png 12w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-990x990.png 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-441x441.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-100x100.png 100w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-800x800.png 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-40x40.png 40w\" data-sizes=\"(max-width: 2000px) 100vw, 2000px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 2000px; --smush-placeholder-aspect-ratio: 2000\/2000;\" \/><noscript><img decoding=\"async\" width=\"2000\" height=\"2000\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2.png\" alt=\"\" class=\"wp-image-8987\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2.png 2000w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-300x300.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-1024x1024.png 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-150x150.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-768x768.png 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-1536x1536.png 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-12x12.png 12w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-990x990.png 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-441x441.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-100x100.png 100w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-800x800.png 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-2-40x40.png 40w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/noscript><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"2000\" height=\"2000\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4.png\" alt=\"\" class=\"wp-image-8989 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4.png 2000w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-300x300.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-1024x1024.png 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-150x150.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-768x768.png 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-1536x1536.png 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-12x12.png 12w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-990x990.png 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-441x441.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-100x100.png 100w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-800x800.png 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-40x40.png 40w\" data-sizes=\"(max-width: 2000px) 100vw, 2000px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 2000px; --smush-placeholder-aspect-ratio: 2000\/2000;\" \/><noscript><img decoding=\"async\" width=\"2000\" height=\"2000\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4.png\" alt=\"\" class=\"wp-image-8989\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4.png 2000w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-300x300.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-1024x1024.png 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-150x150.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-768x768.png 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-1536x1536.png 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-12x12.png 12w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-990x990.png 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-441x441.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-100x100.png 100w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-800x800.png 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-4-40x40.png 40w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/noscript><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"873\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170.png\" alt=\"\" class=\"wp-image-8990 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170.png 2000w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-300x131.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-1024x447.png 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-768x335.png 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-1536x670.png 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-18x8.png 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-990x432.png 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-441x192.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-800x349.png 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-150x65.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-60x26.png 60w\" data-sizes=\"(max-width: 2000px) 100vw, 2000px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 2000px; --smush-placeholder-aspect-ratio: 2000\/873;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"873\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170.png\" alt=\"\" class=\"wp-image-8990\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170.png 2000w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-300x131.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-1024x447.png 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-768x335.png 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-1536x670.png 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-18x8.png 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-990x432.png 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-441x192.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-800x349.png 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-150x65.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-5-e1768270592170-60x26.png 60w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/noscript><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Especificaci\u00f3n:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Impermeable IP65<\/li>\n\n\n\n<li>9 piezas 18W 6 en 1 color RGBAW+ UV<\/li>\n\n\n\n<li>Capacidad de la bater\u00eda:13200MAH<\/li>\n\n\n\n<li>Tiempo de carga:5 horas<\/li>\n\n\n\n<li>Tiempo de uso de la bater\u00eda:<\/li>\n\n\n\n<li>Un color:20 horas,<\/li>\n\n\n\n<li>Encendido de todos los LED: 3 horas,<\/li>\n\n\n\n<li>Modo de funcionamiento autom\u00e1tico: 7 horas<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\"><strong>Par\u00e1metro:<\/strong>\u200b<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Tensi\u00f3n de entrada<\/td><td>AC100V-240V\/ 50-60Hz<\/td><\/tr><tr><td>Mezcla de colores<\/td><td>RGBAW+ UV 6en1<\/td><\/tr><tr><td>Fuente de luz<\/td><td>9 piezas 18W<\/td><\/tr><tr><td>Capacidad de la bater\u00eda<\/td><td>13200MAH<\/td><\/tr><tr><td>Tiempo de carga<\/td><td>5 horas<\/td><\/tr><tr><td>Tiempo de uso de la bater\u00eda<\/td><td>Un color:20 horas<\/td><\/tr><tr><td>Tiempo de uso de la bater\u00eda<\/td><td>Encendido de todos los LED: 3 horas<\/td><\/tr><tr><td>Tiempo de uso de la bater\u00eda<\/td><td>Modo de funcionamiento autom\u00e1tico: 7 horas<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Hora del espect\u00e1culo:<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"557\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-1024x557.jpg\" alt=\"\" class=\"wp-image-8994 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-1024x557.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-300x163.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-768x417.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-18x10.jpg 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-990x538.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-441x240.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-800x435.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-150x82.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-60x33.jpg 60w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4.jpg 1170w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/557;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"557\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-1024x557.jpg\" alt=\"\" class=\"wp-image-8994\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-1024x557.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-300x163.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-768x417.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-18x10.jpg 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-990x538.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-441x240.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-800x435.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-150x82.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4-60x33.jpg 60w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X4.jpg 1170w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"558\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-1024x558.jpg\" alt=\"\" class=\"wp-image-8991 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-1024x558.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-300x163.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-768x418.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-18x10.jpg 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-990x539.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-441x240.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-800x436.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-150x82.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-60x33.jpg 60w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1.jpg 1170w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/558;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"558\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-1024x558.jpg\" alt=\"\" class=\"wp-image-8991\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-1024x558.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-300x163.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-768x418.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-18x10.jpg 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-990x539.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-441x240.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-800x436.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-150x82.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1-60x33.jpg 60w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X1.jpg 1170w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"554\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-1024x554.jpg\" alt=\"\" class=\"wp-image-8993 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-1024x554.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-300x162.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-768x416.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-18x10.jpg 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-990x536.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-441x239.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-800x433.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-150x81.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-60x32.jpg 60w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3.jpg 1170w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/554;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"554\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-1024x554.jpg\" alt=\"\" class=\"wp-image-8993\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-1024x554.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-300x162.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-768x416.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-18x10.jpg 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-990x536.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-441x239.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-800x433.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-150x81.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3-60x32.jpg 60w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X3.jpg 1170w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"559\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-1024x559.jpg\" alt=\"\" class=\"wp-image-8995 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-1024x559.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-300x164.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-768x419.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-18x10.jpg 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-990x541.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-441x241.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-800x437.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-150x82.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-60x33.jpg 60w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5.jpg 1170w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/559;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"559\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-1024x559.jpg\" alt=\"\" class=\"wp-image-8995\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-1024x559.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-300x164.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-768x419.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-18x10.jpg 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-990x541.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-441x241.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-800x437.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-150x82.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5-60x33.jpg 60w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/07\/IP-Battery-B918-X5.jpg 1170w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"QFw9Te BLojaf\">\n<div class=\"hlJJmd\">\n<div class=\"Bmcqed\" dir=\"ltr\">\n<div data-id=\"kvLWu\">Este ba\u00f1ador de pared impermeable IP65 9x18W RGBWA UV es la soluci\u00f3n perfecta alimentada por pilas para bodas y eventos. Con nueve LED 6 en 1 de alta potencia, ofrece una impresionante mezcla de colores y vibrantes efectos UV. Su dise\u00f1o robusto y resistente a la intemperie garantiza un rendimiento fiable tanto en interiores como en exteriores. Alimentado por una bater\u00eda de 13200 mAh, ofrece hasta 20 horas de luz monocolor o 7 horas en modo autom\u00e1tico. Con un tiempo de carga de 5 horas, proporciona una iluminaci\u00f3n brillante e inal\u00e1mbrica para cualquier ocasi\u00f3n, creando fondos atmosf\u00e9ricos inolvidables.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"DVHrxd\">\u00a0<\/div>\n<div class=\"UdTY9 BwTYAc leDWne\" aria-hidden=\"true\" data-location=\"1\">\u00a0<\/div>\n<p>&nbsp;<\/p>\n<blockquote><p>\u00a0<\/p><\/blockquote>\n<p>&nbsp;<\/p>","protected":false},"featured_media":8989,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[83],"product_tag":[212,213,126,202,127],"class_list":{"0":"post-8985","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-battery-wireless-light","7":"product_tag-dmx-wall-washer-bar-lights","8":"product_tag-led-battery-powered-wedding-uplight","9":"product_tag-uplights","10":"product_tag-wireless-battery-uplight","11":"product_tag-wireless-uplights","13":"first","14":"instock","15":"shipping-taxable","16":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/product\/8985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/comments?post=8985"}],"version-history":[{"count":5,"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/product\/8985\/revisions"}],"predecessor-version":[{"id":11916,"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/product\/8985\/revisions\/11916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/media\/8989"}],"wp:attachment":[{"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/media?parent=8985"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/product_brand?post=8985"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/product_cat?post=8985"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lirolight.com\/es\/wp-json\/wp\/v2\/product_tag?post=8985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}