{"id":9680,"date":"2025-09-26T08:31:37","date_gmt":"2025-09-26T08:31:37","guid":{"rendered":"https:\/\/lirolight.com\/?p=9680"},"modified":"2026-04-30T01:29:18","modified_gmt":"2026-04-30T01:29:18","slug":"liro-lite-350w-rgbwal-led-6in1-cob-mini-blinder-light-ip65-splicing-led-blinder-light","status":"publish","type":"post","link":"https:\/\/lirolight.com\/ja\/liro-lite-350w-rgbwal-led-6in1-cob-mini-blinder-light-ip65-splicing-led-blinder-light\/","title":{"rendered":"LIRO-LITE 350w RGBWAL LED 6in1 \u306e\u7a42\u8ef8\u5c0f\u578b Blinder \u30e9\u30a4\u30c8 IP65 \u30b9\u30d7\u30e9\u30a4\u30b7\u30f3\u30b0 LED \u306e Blinder \u30e9\u30a4\u30c8"},"content":{"rendered":"<p class=\"has-background\" style=\"background-color:#eeeeee\">\u3053\u308c\u306f<strong> IP65\u30df\u30cb\u89b3\u5ba2\u30e9\u30a4\u30c8<\/strong> \u306f\u3001\u30de\u30eb\u30c1\u30b7\u30fc\u30f3\u7167\u660e\u306e\u771f\u306e\u300c\u30c8\u30e9\u30f3\u30b9\u30d5\u30a9\u30fc\u30de\u30fc\u300d\u3067\u3059\uff01\u305d\u306e\u6700\u5927\u306e\u7279\u5fb4\u306f\u3001\u30e2\u30b8\u30e5\u30fc\u30eb\u5f0f\u306e\u30c7\u30b6\u30a4\u30f3\u306b\u3042\u308a\u307e\u3059\u30021\u3064\u306e\u30e9\u30a4\u30c8\u306f\u30b3\u30f3\u30d1\u30af\u30c8\u3067\u6301\u3061\u904b\u3073\u3084\u3059\u304f\u3001\u3069\u3093\u306a\u4f1a\u5834\u306b\u3082\u7c21\u5358\u306b\u6301\u3061\u904b\u3079\u307e\u3059\u3002\u8907\u6570\u306e\u30e9\u30a4\u30c8\u3092\u7d44\u307f\u5408\u308f\u305b\u308b\u3053\u3068\u3067\u3001\u76f4\u7dda\u3001\u5186\u5f27\u3001\u30de\u30c8\u30ea\u30c3\u30af\u30b9\u306a\u3069\u3001\u30af\u30ea\u30a8\u30a4\u30c6\u30a3\u30d6\u306a\u5f62\u72b6\u3092\u4f5c\u308a\u51fa\u3059\u3053\u3068\u304c\u3067\u304d\u307e\u3059\u3002DMX512\u30a4\u30f3\u30c6\u30ea\u30b8\u30a7\u30f3\u30c8\u30fb\u30e9\u30a4\u30c6\u30a3\u30f3\u30b0\u30fb\u30b3\u30f3\u30c8\u30ed\u30fc\u30eb\u30fb\u30b7\u30b9\u30c6\u30e0\u306b\u3088\u308a\u3001\u30b0\u30e9\u30c7\u30fc\u30b7\u30e7\u30f3\u306e\u3088\u3046\u306a\u30c0\u30a4\u30ca\u30df\u30c3\u30af\u306a\u30a8\u30d5\u30a7\u30af\u30c8\u3082\u53ef\u80fd\u3067\u3059\u3001 <strong>\u30b9\u30c8\u30ed\u30dc<\/strong>\u305d\u3057\u3066\u3001\u30c1\u30a7\u30a4\u30b9\u3082\u53ef\u80fd\u3067\u3001\u307e\u3055\u306b\u300c1\u3064\u306e\u30e9\u30a4\u30c8\u3067\u4f55\u901a\u308a\u3082\u306e\u4f7f\u3044\u65b9\u304c\u3067\u304d\u3001\u30cb\u30fc\u30ba\u306b\u5408\u308f\u305b\u3089\u308c\u308b\u300d\u306e\u3060\uff01<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"765\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-2-1-1024x765.png\" alt=\"\" class=\"wp-image-9683\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-2-1-1024x765.png 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-2-1-300x224.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-2-1-768x574.png 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-2-1-1536x1147.png 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-2-1-16x12.png 16w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-2-1-990x739.png 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-2-1-441x329.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-2-1-800x597.png 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-2-1-150x112.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-2-1-54x40.png 54w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-2-1.png 1580w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-small-font-size\"><strong><mark style=\"background-color:#000000\" class=\"has-inline-color has-white-color\">\u6280\u8853\u7684\u30d1\u30e9\u30e1\u30fc\u30bf\uff1a<\/mark><\/strong><\/p>\n\n\n\n<p>\u5149\u6e90\uff1a84\u00d73.5W RGBWAL LED<br>\u51fa\u529b\uff1a12700 Lm<br>\u30d3\u30fc\u30e0\u89d2\uff1a46\u00b0\uff08\u30aa\u30d7\u30b7\u30e7\u30f3\uff1a34\uff09<br>\u30d5\u30a3\u30fc\u30eb\u30c9\u89d2\uff1a86\u00b0\uff08\u30aa\u30d7\u30b7\u30e7\u30f3\uff1a56\uff09<br>CT\uff1a1800k\uff5e8500k<br>CRI\uff1a92+<br>IP\u7b49\u7d1a\uff1aIP65<br>\u5869\u5bb3\u306b\u5f37\u3044<br>\u591a\u69d8\u306a\u63a5\u7d9a\u5f62\u72b6\u306b\u5bfe\u5fdc<br>\u30bd\u30fc\u30b9\u5bff\u547d\uff1a&gt;20000 H<br>\u30c1\u30e3\u30f3\u30cd\u30eb\uff1a1 \/ 2 \/ 3 \/ 4 \/ 6 \/ 7 \/ 14 \/ 21 \/ 10-1 \/ 15-1 \/ 10-2 \/ 15-2 CH<br>\u96fb\u5727\uff1aAC 100V-240V 50\/60HZ<br>\u5b9a\u683c\u51fa\u529b\uff1a270W<br>\u8077\u5834\u74b0\u5883\uff1a40\u2103\uff5e45<br>\u30b9\u30bf\u30fc\u30c8\u30a2\u30c3\u30d7\u74b0\u5883\uff1a40\u2103\uff5e45<br>\u30b9\u30c8\u30ed\u30dc\uff1a1\uff5e25HZ<br>LED\u30ea\u30d5\u30ec\u30c3\u30b7\u30e5\u30ec\u30fc\u30c8\uff1a900HZ\u301c25KHZ<br>\u30d7\u30ed\u30c8\u30ab\u30eb\uff1aDMX512\u3001RDM<br>\u30c7\u30fc\u30bf\u30fb\u30b3\u30cd\u30af\u30bf\u30fc3\u30d4\u30f3XLR<br>\u30c7\u30a3\u30b9\u30d7\u30ec\u30a4\u6709\u6a5fEL\u30c7\u30a3\u30b9\u30d7\u30ec\u30a4<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong><mark style=\"background-color:#000000\" class=\"has-inline-color has-white-color\">\u5199\u771f<\/mark><\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"527\" height=\"264\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-3.png\" alt=\"\" class=\"wp-image-9684 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-3.png 527w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-3-300x150.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-3-18x9.png 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-3-441x221.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-3-150x75.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-3-60x30.png 60w\" data-sizes=\"(max-width: 527px) 100vw, 527px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 527px; --smush-placeholder-aspect-ratio: 527\/264;\" \/><noscript><img decoding=\"async\" width=\"527\" height=\"264\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-3.png\" alt=\"\" class=\"wp-image-9684\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-3.png 527w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-3-300x150.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-3-18x9.png 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-3-441x221.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-3-150x75.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-3-60x30.png 60w\" sizes=\"(max-width: 527px) 100vw, 527px\" \/><\/noscript><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"507\" height=\"253\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-4.png\" alt=\"\" class=\"wp-image-9685 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-4.png 507w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-4-300x150.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-4-18x9.png 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-4-441x220.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-4-150x75.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-4-60x30.png 60w\" data-sizes=\"(max-width: 507px) 100vw, 507px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 507px; --smush-placeholder-aspect-ratio: 507\/253;\" \/><noscript><img decoding=\"async\" width=\"507\" height=\"253\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-4.png\" alt=\"\" class=\"wp-image-9685\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-4.png 507w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-4-300x150.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-4-18x9.png 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-4-441x220.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-4-150x75.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-4-60x30.png 60w\" sizes=\"(max-width: 507px) 100vw, 507px\" \/><\/noscript><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"541\" height=\"270\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-5.png\" alt=\"\" class=\"wp-image-9686 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-5.png 541w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-5-300x150.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-5-18x9.png 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-5-441x220.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-5-150x75.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-5-60x30.png 60w\" data-sizes=\"(max-width: 541px) 100vw, 541px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 541px; --smush-placeholder-aspect-ratio: 541\/270;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"541\" height=\"270\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-5.png\" alt=\"\" class=\"wp-image-9686\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-5.png 541w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-5-300x150.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-5-18x9.png 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-5-441x220.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-5-150x75.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-5-60x30.png 60w\" sizes=\"(max-width: 541px) 100vw, 541px\" \/><\/noscript><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"532\" height=\"266\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-6.png\" alt=\"\" class=\"wp-image-9687 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-6.png 532w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-6-300x150.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-6-18x9.png 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-6-441x221.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-6-150x75.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-6-60x30.png 60w\" data-sizes=\"(max-width: 532px) 100vw, 532px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 532px; --smush-placeholder-aspect-ratio: 532\/266;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"532\" height=\"266\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-6.png\" alt=\"\" class=\"wp-image-9687\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-6.png 532w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-6-300x150.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-6-18x9.png 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-6-441x221.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-6-150x75.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/LIRO-LITE-350w-RGBWAL-LED-6in1-COB-Mini-Blinder-Light-IP65-Splicing-LED-Blinder-Light-6-60x30.png 60w\" sizes=\"(max-width: 532px) 100vw, 532px\" \/><\/noscript><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"has-small-font-size\"><strong><mark style=\"background-color:#000000\" class=\"has-inline-color has-white-color\">\u30b5\u30a4\u30ba<\/mark><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"723\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-1024x723.png\" alt=\"\" class=\"wp-image-9688 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-1024x723.png 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-300x212.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-768x543.png 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-1536x1085.png 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-2048x1447.png 2048w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-18x12.png 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-990x699.png 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-441x312.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-800x565.png 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-150x106.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-57x40.png 57w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/723;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"723\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-1024x723.png\" alt=\"\" class=\"wp-image-9688\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-1024x723.png 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-300x212.png 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-768x543.png 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-1536x1085.png 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-2048x1447.png 2048w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-18x12.png 18w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-990x699.png 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-441x312.png 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-800x565.png 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-150x106.png 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/\u5fae\u4fe1\u56fe\u7247_20250926162825-57x40.png 57w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n\n\n\n<p>3.5W\u306eRGBWAL\u9ad8\u6f14\u8272LED\u309284\u500b\u4f7f\u7528\u3057\u3001\u6700\u592712,700\u30eb\u30fc\u30e1\u30f3\u306e\u660e\u308b\u3055\u3092\u5b9f\u73fe\u3057\u305f\u9632\u6c34\u30df\u30cb\u30d6\u30e9\u30a4\u30f3\u30c0\u30fc\u3067\u3059\u3002\u8272\u6e29\u5ea6\u306f1800K\u304b\u30898500K\u307e\u3067\u8abf\u6574\u53ef\u80fd\u3067\u3001CRI\uff08\u6f14\u8272\u8a55\u4fa1\u6570\uff09\u306f92\u3092\u8d85\u3048\u3001\u5fe0\u5b9f\u306a\u8272\u518d\u73fe\u3092\u4fdd\u8a3c\u3057\u307e\u3059\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-1024x768.jpg\" alt=\"\" class=\"wp-image-11117 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-1024x768.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-300x225.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-768x576.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-1536x1152.jpg 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-16x12.jpg 16w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-990x742.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-441x331.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-800x600.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-150x112.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-53x40.jpg 53w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1.jpg 1702w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-1024x768.jpg\" alt=\"\" class=\"wp-image-11117\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-1024x768.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-300x225.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-768x576.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-1536x1152.jpg 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-16x12.jpg 16w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-990x742.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-441x331.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-800x600.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-150x112.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1-53x40.jpg 53w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/1-1.jpg 1702w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n\n\n\n<p>\u6a19\u6e96\u7167\u5c04\u89d246\u00b0\uff08\u30aa\u30d7\u30b7\u30e7\u30f3\u306734\u00b0\uff09\u3001\u5e83\u8996\u91ce\u89d286\u00b0\uff08\u30aa\u30d7\u30b7\u30e7\u30f3\u306756\u00b0\uff09\u3002IP65\u6e96\u62e0\u3067\u5869\u6c34\u5674\u9727\u306b\u5f37\u304f\u3001-40\u2103\uff5e45\u2103\u306e\u904e\u9177\u306a\u4f7f\u7528\u6e29\u5ea6\u306b\u3082\u8010\u3048\u308b\u3002\u5149\u6e90\u306e\u5bff\u547d\u306f20,000\u6642\u9593\u3092\u8d85\u3048\u307e\u3059\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-1024x768.jpg\" alt=\"\" class=\"wp-image-11119 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-1024x768.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-300x225.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-768x576.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-1536x1152.jpg 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-16x12.jpg 16w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-990x742.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-441x331.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-800x600.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-150x112.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-53x40.jpg 53w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2.jpg 1702w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-1024x768.jpg\" alt=\"\" class=\"wp-image-11119\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-1024x768.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-300x225.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-768x576.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-1536x1152.jpg 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-16x12.jpg 16w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-990x742.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-441x331.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-800x600.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-150x112.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2-53x40.jpg 53w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/3-2.jpg 1702w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n\n\n\n<p>1\/2\/3\/4\/6\/7\/14\/21\/10\/1\/15-1\/10-2\/15-2\u306e\u30de\u30eb\u30c1\u30c1\u30e3\u30f3\u30cd\u30eb\u5236\u5fa1\u30e2\u30fc\u30c9\u3092\u642d\u8f09\u3002DMX512\u304a\u3088\u3073RDM\u30d7\u30ed\u30c8\u30b3\u30eb\u3068\u4e92\u63db\u6027\u304c\u3042\u308a\u30013\u30d4\u30f3XLR\u30b3\u30cd\u30af\u30bf\u30fc\u3067\u30c7\u30fc\u30bf\u3092\u9001\u4fe1\u3057\u3001\u76f4\u611f\u7684\u306a\u64cd\u4f5c\u306e\u305f\u3081\u306eOLED\u30c7\u30a3\u30b9\u30d7\u30ec\u30a4\u3092\u5099\u3048\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-1024x768.jpg\" alt=\"\" class=\"wp-image-11122 lazyload\" data-srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-1024x768.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-300x225.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-768x576.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-1536x1152.jpg 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-16x12.jpg 16w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-990x742.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-441x331.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-800x600.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-150x112.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-53x40.jpg 53w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6.jpg 1702w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-1024x768.jpg\" alt=\"\" class=\"wp-image-11122\" srcset=\"https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-1024x768.jpg 1024w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-300x225.jpg 300w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-768x576.jpg 768w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-1536x1152.jpg 1536w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-16x12.jpg 16w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-990x742.jpg 990w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-441x331.jpg 441w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-800x600.jpg 800w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-150x112.jpg 150w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6-53x40.jpg 53w, https:\/\/lirolight.com\/wp-content\/uploads\/2025\/09\/6.jpg 1702w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n\n\n\n<p>900Hz\uff5e25kHz\u306e\u9ad8\u5468\u6ce2LED\u30ea\u30d5\u30ec\u30c3\u30b7\u30e5\u30ec\u30fc\u30c8\u30681\uff5e25Hz\u306e\u30b9\u30c8\u30ed\u30dc\u6a5f\u80fd\u3092\u5099\u3048\u3001\u30e2\u30b8\u30e5\u30fc\u30eb\u5f0f\u30b9\u30d7\u30e9\u30a4\u30b7\u30f3\u30b0\u30c7\u30b6\u30a4\u30f3\u3068\u7d44\u307f\u5408\u308f\u305b\u308b\u3053\u3068\u3067\u3001\u3055\u307e\u3056\u307e\u306a\u5f62\u72b6\u3092\u67d4\u8edf\u306b\u69cb\u7bc9\u3067\u304d\u308b\u305f\u3081\u3001\u5c4b\u5916\u30d1\u30d5\u30a9\u30fc\u30de\u30f3\u30b9\u3084\u30c6\u30fc\u30de\u30d1\u30fc\u30af\u306a\u3069\u306e\u30b7\u30fc\u30f3\u306b\u6700\u9069\u306a\u7167\u660e\u30bd\u30ea\u30e5\u30fc\u30b7\u30e7\u30f3\u3068\u306a\u308b\u3002<\/p>\n\n\n\n<!--more-->\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u3053\u306eIP65\u30df\u30cb\u30fb\u30aa\u30fc\u30c7\u30a3\u30a8\u30f3\u30b9\u30fb\u30e9\u30a4\u30c8\u306f\u3001\u30de\u30eb\u30c1\u30b7\u30fc\u30f3\u7167\u660e\u306e\u771f\u306e\u300c\u30c8\u30e9\u30f3\u30b9\u30d5\u30a9\u30fc\u30de\u30fc\u300d\u3067\u3059\uff01\u3053\u306e\u30e9\u30a4\u30c8\u306e\u6700\u5927\u306e\u7279\u5fb4\u306f\u3001\u30e2\u30b8\u30e5\u30fc\u30eb\u5f0f\u306e\u30c7\u30b6\u30a4\u30f3\u306b\u3042\u308a\u307e\u3059\u3002\u8907\u6570\u306e\u30e9\u30a4\u30c8\u3092\u7d44\u307f\u5408\u308f\u305b\u308b\u3053\u3068\u3067\u3001\u76f4\u7dda\u3001\u5186\u5f27\u3001\u30de\u30c8\u30ea\u30c3\u30af\u30b9\u306a\u3069\u3001\u30af\u30ea\u30a8\u30a4\u30c6\u30a3\u30d6\u306a\u5f62\u72b6\u3092\u4f5c\u308a\u51fa\u3059\u3053\u3068\u304c\u3067\u304d\u307e\u3059\u3002DMX512\u30a4\u30f3\u30c6\u30ea\u30b8\u30a7\u30f3\u30c8\u30fb\u30e9\u30a4\u30c6\u30a3\u30f3\u30b0\u30fb\u30b3\u30f3\u30c8\u30ed\u30fc\u30eb\u30fb\u30b7\u30b9\u30c6\u30e0\u3092\u4f7f\u7528\u3059\u308c\u3070\u3001\u30b0\u30e9\u30c7\u30fc\u30b7\u30e7\u30f3\u3001\u30b9\u30c8\u30ed\u30dc\u3001\u30c1\u30a7\u30a4\u30b9\u306a\u3069\u306e\u30c0\u30a4\u30ca\u30df\u30c3\u30af\u306a\u30a8\u30d5\u30a7\u30af\u30c8\u3082\u53ef\u80fd\uff01\u6280\u8853\u30d1\u30e9\u30e1\u30fc\u30bf\u30fc\u5149\u6e90\uff1a84\u00d73.5W RGBWAL LED\u51fa\u529b\uff1a12700 Lm\u30d3\u30fc\u30e0\u89d2\uff1a46\u00b0\uff08\u30aa\u30d7\u30b7\u30e7\u30f3\uff1a34\u00b0\uff09\u7167\u5c04\u89d2\uff1a86\u00b0\uff08\u30aa\u30d7\u30b7\u30e7\u30f3\uff1a56\u00b0\uff09CT\uff1a1800K ~ 8500KCRI\uff1a92+IP\u5b9a\u683c\uff1aIP65\u8010\u5869\u8150\u98df\u6027\u591a\u69d8\u306a\u30b9\u30d7\u30e9\u30a4\u30b7\u30f3\u30b0\u5f62\u72b6\u306b\u5bfe\u5fdc\u30bd\u30fc\u30b9\u5bff\u547d\uff1a&gt;20000 H\u30c1\u30e3\u30f3\u30cd\u30eb\uff1a1 \/ 2 \/ 3 \/ 4 \/ 6 \/ 7 \/ 14 \/ 21 [...]<\/p>","protected":false},"author":1,"featured_media":9682,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[90],"tags":[446,441,445,443,444],"class_list":["post-9680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-ip-splicing-blinder","tag-ip65-mini-audience-light","tag-ip65-splicing-led-blinder-light","tag-led-cob-light","tag-mini-blinder-light"],"_links":{"self":[{"href":"https:\/\/lirolight.com\/ja\/wp-json\/wp\/v2\/posts\/9680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lirolight.com\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lirolight.com\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lirolight.com\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lirolight.com\/ja\/wp-json\/wp\/v2\/comments?post=9680"}],"version-history":[{"count":2,"href":"https:\/\/lirolight.com\/ja\/wp-json\/wp\/v2\/posts\/9680\/revisions"}],"predecessor-version":[{"id":11123,"href":"https:\/\/lirolight.com\/ja\/wp-json\/wp\/v2\/posts\/9680\/revisions\/11123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lirolight.com\/ja\/wp-json\/wp\/v2\/media\/9682"}],"wp:attachment":[{"href":"https:\/\/lirolight.com\/ja\/wp-json\/wp\/v2\/media?parent=9680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lirolight.com\/ja\/wp-json\/wp\/v2\/categories?post=9680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lirolight.com\/ja\/wp-json\/wp\/v2\/tags?post=9680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}